{"id":22445,"date":"2026-04-22T12:32:00","date_gmt":"2026-04-22T10:32:00","guid":{"rendered":"https:\/\/cittadellascienza.dedadigital.review\/?post_type=event&#038;p=22445"},"modified":"2026-04-22T12:32:02","modified_gmt":"2026-04-22T10:32:02","slug":"didolab-sensazioni-un-viaggio-multisensoriale-tra-dido-e-emozioni-4","status":"publish","type":"event","link":"https:\/\/cittadellascienza.dedadigital.review\/en\/calendario-eventi\/evento\/didolab-sensazioni-un-viaggio-multisensoriale-tra-dido-e-emozioni-4\/","title":{"rendered":"Did\u00f2Lab -&#8220;SensAzioni&#8221;: un viaggio multisensoriale tra Did\u00f2 e Emozioni"},"content":{"rendered":"\n<p>I bambini esploreranno i cinque sensi attraverso la tattilit\u00e0 del Did\u00f2, sperimentando forme, colori e consistenze. Le attivit\u00e0 saranno guidate da personaggi immaginari ispirati al mondo delle emozioni, che accompagneranno i partecipanti in un percorso creativo e sensoriale. Un\u2019occasione per imparare a dare \u201cforma\u201d non solo alla materia, ma anche alle proprie emozioni, in un contesto accogliente e curato, pensato per stimolare la creativit\u00e0 dei pi\u00f9 piccoli.<\/p>\n\n\n\n<p>L&#8217;evento \u00e8 realizzato in collaborazione con \u201cGiotto colore ufficiale delle attivit\u00e0 educational di Citt\u00e0 della Scienza\u201d.<\/p>\n\n\n    <section class=\"gblock info_box_selector light-grey-bg bg-pos-h-center bg-pos-v-center mb-0\"  aria-labelledby=\"section-1\"><div class=\"container px-0 block_count_1\" data-blockcount=\"1\"><div class=\"row\">    <div class=\"col-12\">\n        <div class=\"container\">\n            <div class=\"row\">\n\n                <div class=\"col-12\">\n                                    <\/div>\n                                <div class=\"col-12\">\n                    \n<h2 class=\"wp-block-heading\" style=\"margin-top:20px;margin-bottom:20px;font-size:28px\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-red-color\">FOR<strong> INFO <\/strong>AND<strong> CONTACTS<\/strong><\/mark><\/h2>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\r\n\r\n\r\n    <section class=\"gblock section_title transparent-bg bg-pos-h-center bg-pos-v-center mb-0\"  aria-labelledby=\"section-2\"><div class=\"container px-0 block_count_2\" data-blockcount=\"2\"><div class=\"row\">\r\n\t<div class=\"col-12\">\r\n\t\t<h2 class=\"mb-2 text-start red\" id=\"section-2\">\r\n\t\t\t\t\t\t\t<i class=\"me-2 title-icon red fa-classic fa-solid fa-phone\"><\/i>\r\n\t\t\t\t\t\t<span class=\"\">Phone<\/span>\r\n\t\t<\/h2>\r\n\t<\/div>\r\n\t\t\t<div class=\"col-12 pb-2\">\r\n\t\t\t<div class=\"border-separator\"><\/div>\r\n\t\t<\/div>\r\n\t    <\/div><\/div><\/section>\r\n\n\n\n<p><strong>For info and reservations<\/strong> is available<br\/>the Contact Center of Citt\u00e0 della Scienza:<br\/><strong>Tel.<\/strong> (+39) <a href=\"tel:081%207352222\">081 7352.222<\/a><\/p>\n\n\n\r\n\r\n\r\n    <section class=\"gblock section_title transparent-bg bg-pos-h-center bg-pos-v-center mb-0\"  aria-labelledby=\"section-3\"><div class=\"container px-0 block_count_3\" data-blockcount=\"3\"><div class=\"row\">\r\n\t<div class=\"col-12\">\r\n\t\t<h2 class=\"mb-2 text-start red\" id=\"section-3\">\r\n\t\t\t\t\t\t\t<i class=\"me-2 title-icon red fa-classic fa-solid fa-at\"><\/i>\r\n\t\t\t\t\t\t<span class=\"\">Mail<\/span>\r\n\t\t<\/h2>\r\n\t<\/div>\r\n\t\t\t<div class=\"col-12 pb-2\">\r\n\t\t\t<div class=\"border-separator\"><\/div>\r\n\t\t<\/div>\r\n\t    <\/div><\/div><\/section>\r\n\n\n\n<p><strong>Info and reservations <\/strong>are available<br\/>the email <strong><a href=\"mailto:contact@cittadellascienza.it\">contact@cittadellascienza.it<\/a><\/strong><\/p>\n\n\n\r\n\r\n\r\n    <section class=\"gblock section_title transparent-bg bg-pos-h-center bg-pos-v-center mb-0\"  aria-labelledby=\"section-4\"><div class=\"container px-0 block_count_4\" data-blockcount=\"4\"><div class=\"row\">\r\n\t<div class=\"col-12\">\r\n\t\t<h2 class=\"mb-2 text-start red\" id=\"section-4\">\r\n\t\t\t\t\t\t\t<i class=\"me-2 title-icon red fa-classic fa-brands fa-whatsapp\"><\/i>\r\n\t\t\t\t\t\t<span class=\"\">Whatsapp<\/span>\r\n\t\t<\/h2>\r\n\t<\/div>\r\n\t\t\t<div class=\"col-12 pb-2\">\r\n\t\t\t<div class=\"border-separator\"><\/div>\r\n\t\t<\/div>\r\n\t    <\/div><\/div><\/section>\r\n\n\n\n<p><strong>Whatsapp number:<\/strong> 329 463 1667<br\/><em>The service operates from Monday to Friday from 08:30 to 17:00 hours<\/em><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\r\n\r\n\r\n    <section class=\"gblock section_title transparent-bg bg-pos-h-center bg-pos-v-center mb-0\"  aria-labelledby=\"section-5\"><div class=\"container px-0 block_count_5\" data-blockcount=\"5\"><div class=\"row\">\r\n\t<div class=\"col-12\">\r\n\t\t<h2 class=\"mb-2 text-start red\" id=\"section-5\">\r\n\t\t\t\t\t\t\t<i class=\"me-2 title-icon red fa-classic fa-solid fa-ticket\"><\/i>\r\n\t\t\t\t\t\t<span class=\"\">Ticket office<\/span>\r\n\t\t<\/h2>\r\n\t<\/div>\r\n\t\t\t<div class=\"col-12 pb-2\">\r\n\t\t\t<div class=\"border-separator\"><\/div>\r\n\t\t<\/div>\r\n\t    <\/div><\/div><\/section>\r\n\n\n\n<p><strong>Tickets can be purchased online at Etes or <\/strong><br\/><strong>at the ticket office at Citt\u00e0 della Scienza (at the infopoint).<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-red-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/www.etes.it\/cPage\/link\/10129\/\/41\"><strong>BUY YOUR TICKET ONLINE AT ETES.CO.UK<\/strong><\/a><\/div>\n<\/div>\n\n\n\r\n\r\n\r\n    <section class=\"gblock section_title transparent-bg bg-pos-h-center bg-pos-v-center mb-0\"  aria-labelledby=\"section-6\"><div class=\"container px-0 block_count_6\" data-blockcount=\"6\"><div class=\"row\">\r\n\t<div class=\"col-12\">\r\n\t\t<h2 class=\"mb-2 text-start red\" id=\"section-6\">\r\n\t\t\t\t\t\t\t<i class=\"me-2 title-icon red fa-classic fa-regular fa-heart\"><\/i>\r\n\t\t\t\t\t\t<span class=\"\">Follow us<\/span>\r\n\t\t<\/h2>\r\n\t<\/div>\r\n\t\t\t<div class=\"col-12 pb-2\">\r\n\t\t\t<div class=\"border-separator\"><\/div>\r\n\t\t<\/div>\r\n\t    <\/div><\/div><\/section>\r\n\n\n\n<ul class=\"wp-block-social-links is-layout-flex wp-block-social-links-is-layout-flex\"><li class=\"wp-social-link wp-social-link-facebook  wp-block-social-link\"><a href=\"https:\/\/www.facebook.com\/cittadellascienza\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12 2C6.5 2 2 6.5 2 12c0 5 3.7 9.1 8.4 9.9v-7H7.9V12h2.5V9.8c0-2.5 1.5-3.9 3.8-3.9 1.1 0 2.2.2 2.2.2v2.5h-1.3c-1.2 0-1.6.8-1.6 1.6V12h2.8l-.4 2.9h-2.3v7C18.3 21.1 22 17 22 12c0-5.5-4.5-10-10-10z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Facebook<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-instagram  wp-block-social-link\"><a href=\"https:\/\/www.instagram.com\/cittadellascienza\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M12,4.622c2.403,0,2.688,0.009,3.637,0.052c0.877,0.04,1.354,0.187,1.671,0.31c0.42,0.163,0.72,0.358,1.035,0.673 c0.315,0.315,0.51,0.615,0.673,1.035c0.123,0.317,0.27,0.794,0.31,1.671c0.043,0.949,0.052,1.234,0.052,3.637 s-0.009,2.688-0.052,3.637c-0.04,0.877-0.187,1.354-0.31,1.671c-0.163,0.42-0.358,0.72-0.673,1.035 c-0.315,0.315-0.615,0.51-1.035,0.673c-0.317,0.123-0.794,0.27-1.671,0.31c-0.949,0.043-1.233,0.052-3.637,0.052 s-2.688-0.009-3.637-0.052c-0.877-0.04-1.354-0.187-1.671-0.31c-0.42-0.163-0.72-0.358-1.035-0.673 c-0.315-0.315-0.51-0.615-0.673-1.035c-0.123-0.317-0.27-0.794-0.31-1.671C4.631,14.688,4.622,14.403,4.622,12 s0.009-2.688,0.052-3.637c0.04-0.877,0.187-1.354,0.31-1.671c0.163-0.42,0.358-0.72,0.673-1.035 c0.315-0.315,0.615-0.51,1.035-0.673c0.317-0.123,0.794-0.27,1.671-0.31C9.312,4.631,9.597,4.622,12,4.622 M12,3 C9.556,3,9.249,3.01,8.289,3.054C7.331,3.098,6.677,3.25,6.105,3.472C5.513,3.702,5.011,4.01,4.511,4.511 c-0.5,0.5-0.808,1.002-1.038,1.594C3.25,6.677,3.098,7.331,3.054,8.289C3.01,9.249,3,9.556,3,12c0,2.444,0.01,2.751,0.054,3.711 c0.044,0.958,0.196,1.612,0.418,2.185c0.23,0.592,0.538,1.094,1.038,1.594c0.5,0.5,1.002,0.808,1.594,1.038 c0.572,0.222,1.227,0.375,2.185,0.418C9.249,20.99,9.556,21,12,21s2.751-0.01,3.711-0.054c0.958-0.044,1.612-0.196,2.185-0.418 c0.592-0.23,1.094-0.538,1.594-1.038c0.5-0.5,0.808-1.002,1.038-1.594c0.222-0.572,0.375-1.227,0.418-2.185 C20.99,14.751,21,14.444,21,12s-0.01-2.751-0.054-3.711c-0.044-0.958-0.196-1.612-0.418-2.185c-0.23-0.592-0.538-1.094-1.038-1.594 c-0.5-0.5-1.002-0.808-1.594-1.038c-0.572-0.222-1.227-0.375-2.185-0.418C14.751,3.01,14.444,3,12,3L12,3z M12,7.378 c-2.552,0-4.622,2.069-4.622,4.622S9.448,16.622,12,16.622s4.622-2.069,4.622-4.622S14.552,7.378,12,7.378z M12,15 c-1.657,0-3-1.343-3-3s1.343-3,3-3s3,1.343,3,3S13.657,15,12,15z M16.804,6.116c-0.596,0-1.08,0.484-1.08,1.08 s0.484,1.08,1.08,1.08c0.596,0,1.08-0.484,1.08-1.08S17.401,6.116,16.804,6.116z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">Instagram<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-linkedin  wp-block-social-link\"><a href=\"https:\/\/www.linkedin.com\/company\/cittadellascienza\/\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M19.7,3H4.3C3.582,3,3,3.582,3,4.3v15.4C3,20.418,3.582,21,4.3,21h15.4c0.718,0,1.3-0.582,1.3-1.3V4.3 C21,3.582,20.418,3,19.7,3z M8.339,18.338H5.667v-8.59h2.672V18.338z M7.004,8.574c-0.857,0-1.549-0.694-1.549-1.548 c0-0.855,0.691-1.548,1.549-1.548c0.854,0,1.547,0.694,1.547,1.548C8.551,7.881,7.858,8.574,7.004,8.574z M18.339,18.338h-2.669 v-4.177c0-0.996-0.017-2.278-1.387-2.278c-1.389,0-1.601,1.086-1.601,2.206v4.249h-2.667v-8.59h2.559v1.174h0.037 c0.356-0.675,1.227-1.387,2.526-1.387c2.703,0,3.203,1.779,3.203,4.092V18.338z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">LinkedIn<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-youtube  wp-block-social-link\"><a href=\"https:\/\/www.youtube.com\/@citt%C3%A0dellascienzanapoli\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M21.8,8.001c0,0-0.195-1.378-0.795-1.985c-0.76-0.797-1.613-0.801-2.004-0.847c-2.799-0.202-6.997-0.202-6.997-0.202 h-0.009c0,0-4.198,0-6.997,0.202C4.608,5.216,3.756,5.22,2.995,6.016C2.395,6.623,2.2,8.001,2.2,8.001S2,9.62,2,11.238v1.517 c0,1.618,0.2,3.237,0.2,3.237s0.195,1.378,0.795,1.985c0.761,0.797,1.76,0.771,2.205,0.855c1.6,0.153,6.8,0.201,6.8,0.201 s4.203-0.006,7.001-0.209c0.391-0.047,1.243-0.051,2.004-0.847c0.6-0.607,0.795-1.985,0.795-1.985s0.2-1.618,0.2-3.237v-1.517 C22,9.62,21.8,8.001,21.8,8.001z M9.935,14.594l-0.001-5.62l5.404,2.82L9.935,14.594z\"><\/path><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">YouTube<\/span><\/a><\/li>\n\n<li class=\"wp-social-link wp-social-link-x  wp-block-social-link\"><a href=\"https:\/\/x.com\/cittascienza\" class=\"wp-block-social-link-anchor\"><svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M13.982 10.622 20.54 3h-1.554l-5.693 6.618L8.745 3H3.5l6.876 10.007L3.5 21h1.554l6.012-6.989L15.868 21h5.245l-7.131-10.378Zm-2.128 2.474-.697-.997-5.543-7.93H8l4.474 6.4.697.996 5.815 8.318h-2.387l-4.745-6.787Z\" \/><\/svg><span class=\"wp-block-social-link-label screen-reader-text\">X<\/span><\/a><\/li><\/ul>\n<\/div>\n<\/div>\n\n\n                    <\/divc>\n                <\/div>\n            <\/div>\n        <\/div>\n        <\/div><\/div><\/section>    ","protected":false},"excerpt":{"rendered":"<p>I bambini esploreranno i cinque sensi attraverso la tattilit\u00e0 del Did\u00f2, sperimentando forme, colori e consistenze. Le attivit\u00e0 saranno guidate da personaggi immaginari ispirati al mondo delle emozioni, che accompagneranno i partecipanti in un percorso creativo e sensoriale. Un\u2019occasione per imparare a dare \u201cforma\u201d non solo alla materia, ma anche alle proprie emozioni, in un [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":22059,"template":"","meta":{"_acf_changed":true},"event-venue":[75],"event-category":[45],"event-tag":[274],"target":[71],"class_list":["post-22445","event","type-event","status-publish","has-post-thumbnail","hentry","event-venue-iv-piano-corporea-sala-grande--citta-della-scienza","event-category-interactive-lab","event-tag-frutta-e-verdura","target-3-6-anni"],"acf":[],"_links":{"self":[{"href":"https:\/\/cittadellascienza.dedadigital.review\/en\/wp-json\/wp\/v2\/event\/22445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cittadellascienza.dedadigital.review\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/cittadellascienza.dedadigital.review\/en\/wp-json\/wp\/v2\/types\/event"}],"author":[{"embeddable":true,"href":"https:\/\/cittadellascienza.dedadigital.review\/en\/wp-json\/wp\/v2\/users\/3"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cittadellascienza.dedadigital.review\/en\/wp-json\/wp\/v2\/media\/22059"}],"wp:attachment":[{"href":"https:\/\/cittadellascienza.dedadigital.review\/en\/wp-json\/wp\/v2\/media?parent=22445"}],"wp:term":[{"taxonomy":"event-venue","embeddable":true,"href":"https:\/\/cittadellascienza.dedadigital.review\/en\/wp-json\/wp\/v2\/event-venue?post=22445"},{"taxonomy":"event-category","embeddable":true,"href":"https:\/\/cittadellascienza.dedadigital.review\/en\/wp-json\/wp\/v2\/event-category?post=22445"},{"taxonomy":"event-tag","embeddable":true,"href":"https:\/\/cittadellascienza.dedadigital.review\/en\/wp-json\/wp\/v2\/event-tag?post=22445"},{"taxonomy":"target","embeddable":true,"href":"https:\/\/cittadellascienza.dedadigital.review\/en\/wp-json\/wp\/v2\/target?post=22445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}